{"id":3533,"date":"2026-01-27T12:00:38","date_gmt":"2026-01-27T11:00:38","guid":{"rendered":"https:\/\/www.autonocion.com\/motornocion\/?p=3533"},"modified":"2026-02-02T11:23:20","modified_gmt":"2026-02-02T10:23:20","slug":"gobierno-bloquea-plan-auto","status":"publish","type":"post","link":"https:\/\/www.autonocion.com\/motornocion\/gobierno-bloquea-plan-auto\/","title":{"rendered":"El Gobierno sigue bloqueando el plan Auto+ y el mercado de coches el\u00e9ctricos se desespera en Espa\u00f1a"},"content":{"rendered":"<p>Las ventas de <a href=\"https:\/\/www.autonocion.com\/motornocion\/bmw-record-ventas-x1\/\"><strong>coches el\u00e9ctricos<\/strong><\/a> atraviesan un momento delicado, y culpa de ello lo tiene el Gobierno de <strong>Pedro S\u00e1nchez<\/strong>. Hace unos meses, el Presidente anunci\u00f3 el <strong>plan Auto+<\/strong>, que ven\u00eda a sustituir al <strong>Moves III,<\/strong> lo que traer\u00eda consigo una serie de medidas para impulsar la venta de veh\u00edculos el\u00e9ctricos en nuestro pa\u00eds. Pero tras el anuncio, nada de nada, el plan est\u00e1 paralizado, hay bloqueo entre ministerios y las nuevas medidas, no solo no llegan, no parecen que vayan a llegar en un corto espacio de tiempo. Este ha derivado en una reducci\u00f3n de pedidos, no hay datos sobre ventas, apenas ha transcurrido un mes del 2026, pero el sector se muestra muy preocupante ante la falta de apoyo para impulsar las ventas. Las demandas, ante la falta de ayudas, caen en picado.<\/p>\n<h2>El plan Auto+<\/h2>\n<p>Todo viene del pulso entre los ministerios de <strong>Industria<\/strong> y el de <strong>Econom\u00eda<\/strong>. Todo parec\u00eda listo para que en enero entrara en vigor el <a href=\"https:\/\/www.autonocion.com\/el-plan-auto-y-sus-ayudas-en-el-limbo-la-nueva-idea-del-gobierno-es-buena-pero-no-le-gusta-a-los-fabricantes\/\"><strong>plan Auto+<\/strong><\/a>. El borrador parec\u00eda aprobado y se esperaba que quedara aprobado a comienzos de este 20226. Junto con <strong>Anfac<\/strong> y <strong>Faconauto<\/strong>, el trabajo t\u00e9cnico estaba hecho y desde Industria se dec\u00eda que estaba todo hecho. Pero el proceso se detuvo cuando desde el ministerio de econom\u00eda se quiso introducir un sistema para medir la huella de carbono, y de esta manera, decidir que veh\u00edculos y cu\u00e1les no pod\u00edan incluirse en este nuevo plan de ayudas.<\/p>\n<p>La idea era poder conocer toda la huella que puede generar cada uno de los veh\u00edculos en el plan, desde la fabricaci\u00f3n, la contaminaci\u00f3n en circulaci\u00f3n, o lo que supone reciclarlo una vez que llegara al final de su vida \u00fatil. Con este sistema, miles de veh\u00edculos que en un principio podr\u00edan estar dentro del plan, corren el riesgo de quedarse fuera.<\/p>\n<p>Esta idea de <strong>Econom\u00eda<\/strong> chocaba frontalmente con el borrador ya aprobado por <strong>Industria<\/strong>, mucho m\u00e1s flexible, con ayudas mayores para los coches construidos en Europa, pero sin apartar a los de otros lugares del mundo. Con la nueva idea de econom\u00eda, otros coches construidos fuera de territorio comunitario, y continental en general, se pueden quedar fuera. M\u00e1s all\u00e1 de la venta de autom\u00f3viles, el sector teme que, de aplicarse estas medidas, se frenen las inversiones extranjeras y genere tensiones comerciales.<\/p>\n<h2>Se hunden las ventas<\/h2>\n<p>Aunque a\u00fan no hay datos oficiales en este <strong>2026<\/strong>, todav\u00eda no ha concluido el primer mes del a\u00f1o para tener una valoraci\u00f3n real del impacto que supone la ausencia de un plan para la compra de veh\u00edculos el\u00e9ctricos, el sector ya vaticina el primer desastre de la nueva temporada. La demanda est\u00e1 muy por debajo de cuando hab\u00eda ayudas y, por tanto, las ventas se reducen. Por el momento, se calcula un descenso del <strong>10% respecto a enero de 2025<\/strong>.<\/p>\n<p>El anuncio del presidente del Gobierno fue una bocanada de optimismo para un sector que ha evidenciado la realidad, que dos meses despu\u00e9s de las palabras de<strong> Pedro S\u00e1nchez,<\/strong> no hay nada de nada.<\/p>\n<p>Las ayudas podr\u00edan situarse en torno a los 4.000 y los 4.500 euros por cada coche el\u00e9ctrico. Esta cifra ayuda, aun siendo inferior a las ayudas de hasta 7.000 euros del <a href=\"https:\/\/www.autonocion.com\/plan-auto-plus-ayudas-4500-euros-retroactivas-2026\/\"><strong>plan Moves III<\/strong><\/a>. Tampoco convence el presupuesto para el nuevo plan de unos 400 millones, inferior al anterior, pero claro, mucho mejor que no tener nada. Y por \u00faltimo, los compradores desconf\u00edan de que las ayudas sean retroactivas, es decir, no se arriesgan a comprar un coche ahora sabiendo que esa ayuda pueda no llegar nunca, prefieren esperar a que el Gobierno mueva ficha y confirme.<\/p>\n<h2>Una soluci\u00f3n urgente<\/h2>\n<p>El sector del autom\u00f3vil clama por una soluci\u00f3n urgente: el primer mes ya est\u00e1 perdido, pero todav\u00eda se puede mejorar si se lleva a cabo cuanto antes. De momento, el gobierno no se pronuncia y la falta de movimientos, supone un golpe directo, no solo al sector de la automoci\u00f3n, sino tambi\u00e9n a la econom\u00eda global del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las ventas de coches el\u00e9ctricos atraviesan un momento delicado, y culpa de ello lo tiene el Gobierno de Pedro S\u00e1nchez. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"El Gobierno sigue bloqueando el plan Auto+ y el mercado de coches el\u00e9ctricos se desespera en Espa\u00f1a\" class=\"read-more button\" href=\"https:\/\/www.autonocion.com\/motornocion\/gobierno-bloquea-plan-auto\/#more-3533\" aria-label=\"Leer m\u00e1s sobre El Gobierno sigue bloqueando el plan Auto+ y el mercado de coches el\u00e9ctricos se desespera en Espa\u00f1a\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":3534,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","resize-featured-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/posts\/3533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/comments?post=3533"}],"version-history":[{"count":3,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/posts\/3533\/revisions"}],"predecessor-version":[{"id":3920,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/posts\/3533\/revisions\/3920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/media\/3534"}],"wp:attachment":[{"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/media?parent=3533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/categories?post=3533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autonocion.com\/motornocion\/wp-json\/wp\/v2\/tags?post=3533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}